{"id":101335,"date":"2023-05-09T13:58:05","date_gmt":"2023-05-09T11:58:05","guid":{"rendered":"https:\/\/factorialhr.com\/blog\/?p=101335"},"modified":"2023-05-19T15:01:14","modified_gmt":"2023-05-19T13:01:14","slug":"ser-escuchados-trabajo","status":"publish","type":"post","link":"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/","title":{"rendered":"Qu\u00e9 hacer si sientes que no eres escuchado en las reuniones de trabajo"},"content":{"rendered":"<p><strong><i>Te damos algunos trucos para ser escuchado efectivamente en tu entorno de trabajo.<\/i><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Casi todos hemos sentido algo as\u00ed: estamos en una reuni\u00f3n, decimos algo, pero parece que las personas a nuestro alrededor siguen hablando como si tal cosa, como si no nos hubieran escuchado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta situaci\u00f3n, que puede ocurrir en nuestra vida diaria, es especialmente dolorosa en nuestro puesto de trabajo, donde nos puede hacer sentir muy poco valorados, superfluos e incluso hacernos temer por nuestro <a href=\"https:\/\/factorialhr.co\/blog\/reskilling-y-upskilling\/\">futuro en la empresa.<\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Obviamente, es posible reconducir esta situaci\u00f3n. <strong>Hasta los CEOs m\u00e1s importantes del mundo se han sentido alguna vez as\u00ed<\/strong>, la diferencia es que ellos aprendieron a superar este problema y a <a href=\"https:\/\/factorialhr.co\/blog\/feedback-y-comunicacion-abierta\/\">hacerse escuchar.<\/a>\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero seg\u00fan escribi\u00f3 la profesora Amanda Nimon-Peters en un art\u00edculo para<\/span><a href=\"https:\/\/www.psychologytoday.com\/us\/blog\/the-leadership-brief\/202207\/the-science-who-speaks-in-team-meetings\"> <i><span style=\"font-weight: 400;\">Psychology Today<\/span><\/i><\/a><span style=\"font-weight: 400;\">, para aprender a c\u00f3mo influir en los equipos en los que participamos, lo primero que hay que hacer es comprender c\u00f3mo funciona el cerebro humano a la hora de establecer clasificaciones de estatus durante una reuni\u00f3n.<\/span><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot; \n &lt;!--HubSpot Call-to-Action Code --&gt;\n    &lt;span class=&quot;hs-cta-wrapper&quot; id=&quot;hs-cta-wrapper-fe3e673d-2bb6-4095-a5ae-dd8666aa067f&quot;&gt;\n        &lt;span class=&quot;hs-cta-node hs-cta-fe3e673d-2bb6-4095-a5ae-dd8666aa067f&quot; id=&quot;fe3e673d-2bb6-4095-a5ae-dd8666aa067f&quot;&gt;\n            &lt;a href=&quot;https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/4960096\/fe3e673d-2bb6-4095-a5ae-dd8666aa067f&quot;&gt;\n                &lt;img class=&quot;lazyload hs-cta-img&quot; id=&quot;hs-cta-img-fe3e673d-2bb6-4095-a5ae-dd8666aa067f&quot; style=&quot;border-width:0px;&quot; src=&quot;https:\/\/no-cache.hubspot.com\/cta\/default\/4960096\/fe3e673d-2bb6-4095-a5ae-dd8666aa067f.png&quot;  alt=&quot;\u201cebook&quot; width=&quot;\u201c900\u201d&quot; height=&quot;\u201c308\u201d&quot; \/&gt;\n            &lt;\/a&gt;\n        &lt;\/span&gt;\n        &lt;script type=&quot;text\/javascript&quot;&gt;\n            function loadCTA(){\n                window.hbspt.cta.load(4960096, &#039;fe3e673d-2bb6-4095-a5ae-dd8666aa067f&#039;, {&#039;region&#039;: &#039;eu1&#039;})\n            }\n            if(window.hbspt){\n                loadCTA()\n            }else{\n                Defer.js(\n                    &#039;https:\/\/js.hubspot.com\/cta\/current.js&#039;,\n                    &#039;hubspotCTA&#039;, \n                    0, \n                    loadCTA\n                );\n            }\n        &lt;\/script&gt;\n    &lt;\/span&gt;\n&lt;!-- end HubSpot Call-to-Action Code --&gt;\n&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:513,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0}\"> \n <!--HubSpot Call-to-Action Code -->\n    <span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-fe3e673d-2bb6-4095-a5ae-dd8666aa067f\">\n        <span class=\"hs-cta-node hs-cta-fe3e673d-2bb6-4095-a5ae-dd8666aa067f\" id=\"fe3e673d-2bb6-4095-a5ae-dd8666aa067f\">\n            <a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/4960096\/fe3e673d-2bb6-4095-a5ae-dd8666aa067f\">\n                <img decoding=\"async\" class=\"lazyload hs-cta-img\" id=\"hs-cta-img-fe3e673d-2bb6-4095-a5ae-dd8666aa067f\" style=\"border-width:0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4960096\/fe3e673d-2bb6-4095-a5ae-dd8666aa067f.png\"  alt=\"\u201cebook\" width=\"\u201c900\u201d\" height=\"\u201c308\u201d\" \/>\n            <\/a>\n        <\/span>\n        <script type=\"text\/javascript\">\n            function loadCTA(){\n                window.hbspt.cta.load(4960096, 'fe3e673d-2bb6-4095-a5ae-dd8666aa067f', {'region': 'eu1'})\n            }\n            if(window.hbspt){\n                loadCTA()\n            }else{\n                Defer.js(\n                    'https:\/\/js.hubspot.com\/cta\/current.js',\n                    'hubspotCTA', \n                    0, \n                    loadCTA\n                );\n            }\n        <\/script>\n    <\/span>\n<!-- end HubSpot Call-to-Action Code -->\n<\/span><\/p>\n<h2><b>C\u00f3mo clasificamos a las personas en una reuni\u00f3n<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Cuando un grupo de personas se re\u00fane para <a href=\"https:\/\/factorialhr.co\/blog\/trabajo-en-equipo\/\">formar un equipo<\/a>, se realiza casi de manera instant\u00e1nea una organizaci\u00f3n. Esto se conoce como clasificaci\u00f3n de estatus y es una especie de consenso impl\u00edcito sobre qui\u00e9n tiene potencial para realizar una contribuci\u00f3n valiosa en el grupo y qui\u00e9n no.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este proceso puede ser consciente o inconsciente, y los resultados suelen ser bastante similares entre los diferentes miembros de un mismo grupo. Los factores que definen esta importancia dentro del grupo suelen variar poco de una cultura a otra.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El resultado de este proceso de clasificaci\u00f3n tiene un impacto significativo en qui\u00e9n ejerce influencia en el grupo y en qui\u00e9n no. <strong>Los miembros del equipo con un estatus m\u00e1s alto ser\u00e1n m\u00e1s escuchados en el trabajo, menos interrumpidos y se les hablar\u00e1 y mirar\u00e1 con m\u00e1s frecuencia que a los dem\u00e1s.<\/strong> Si un miembro del equipo que se perciba como de \u201cbajo\u201d estatus habla m\u00e1s de lo que se considerar\u00eda apropiado para \u00e9l, se considerar\u00e1 que ha hablado demasiado. Incluso aunque en t\u00e9rminos absolutos hable mucho menos que otros.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, cuanto mayor es el tama\u00f1o del grupo, m\u00e1s desigual es la divisi\u00f3n de la participaci\u00f3n en la discusi\u00f3n dentro del equipo. <\/span><a href=\"https:\/\/www.eui.eu\/Documents\/DepartmentsCentres\/SPS\/ResearchAndTeaching\/Correll-and-Ridgeway-Expectations-state-theory.pdf\"><span style=\"font-weight: 400;\">En un estudio de 2006 realizado por los profesores S. J. Correll y C. L. Ridgeway<\/span><\/a><span style=\"font-weight: 400;\">, se calcul\u00f3 que en un grupo de tres personas, el miembro con el estatus m\u00e1s alto controla alrededor del 47% del tiempo del grupo, mientras que el segundo y el tercer miembro controlan alrededor del 30% y 23%, respectivamente.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A medida que el grupo crece, la persona con el estatus m\u00e1s alto sigue controlando alrededor del 50% de la conversaci\u00f3n, mientras que el 50% restante se divide entre todos los dem\u00e1s miembros. En consecuencia, en un grupo de ocho o m\u00e1s personas, algunos miembros apenas hablan o son escuchados en el trabajo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por lo tanto, <strong>es importante que los l\u00edderes y los miembros del equipo sean conscientes de estos procesos y trabajen activamente para garantizar una distribuci\u00f3n justa y equitativa de la participaci\u00f3n en la discusi\u00f3n del equipo.<\/strong> La <a href=\"https:\/\/factorialhr.co\/blog\/inclusion-laboral\/\">inclusi\u00f3n y la diversidad<\/a> son fundamentales para fomentar la creatividad y la innovaci\u00f3n en el equipo, y es esencial que se promuevan pr\u00e1cticas que permitan que todos los miembros del equipo contribuyan de manera efectiva y equitativa.<\/span><\/p>\n<p><em><strong>Te puede interesar \ud83d\udc49\u00a0<a href=\"https:\/\/factorialhr.co\/blog\/test-de-inteligencia\/\">Test de inteligencia: Aplicaci\u00f3n en la selecci\u00f3n de personal<\/a><\/strong><\/em><\/p>\n<h2><b>\u00bfQu\u00e9 factores aumentan el estatus percibido?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Aunque en el entorno laboral la veteran\u00eda puede jugar un papel muy importante a la hora de tener m\u00e1s estatus (cuando est\u00e1 el jefe se espera que hable m\u00e1s que cualquier otro miembro del equipo), la apariencia f\u00edsica todav\u00eda tiene un papel muy importante en la influencia de cada uno de los miembros del equipo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por ejemplo, aunque <a href=\"https:\/\/factorialhr.co\/blog\/cuotas-de-genero-en-empresas\/\">la tendencia est\u00e1 empezando a equilibrarse<\/a>, a\u00fan siguen siendo los hombres quienes tienen m\u00e1s probabilidades de tener un estatus alto que las mujeres, y aquellos que son m\u00e1s altos y m\u00e1s atractivos tambi\u00e9n tienen una ventaja en la clasificaci\u00f3n del estatus. Adem\u00e1s, aunque suene muy mal, aquellas personas que son de raza blanca tambi\u00e9n tienden a tener un estatus m\u00e1s alto que los de otras razas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fuera de la apariencia f\u00edsica, la fluidez utilizando el lenguaje tambi\u00e9n puede influir en el estatus. <strong>Los hablantes no nativos a menudo tienen menos tiempo para hablar que los hablantes nativos. <\/strong>Este factor es determinante en algunos contextos donde el lenguaje juega un factor determinante para que un colaborador sea escuchado en el trabajo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por lo tanto, estas clasificaciones suelen ser inconscientes y estar basadas en factores que no tienen nada que ver con las habilidades y la capacidad de <a href=\"https:\/\/factorialhr.co\/blog\/aprendizaje-intergeneracional\/\">contribuir al equipo<\/a>, <strong>adem\u00e1s de ser pol\u00edticamente muy incorrectas.<\/strong><\/span><\/p>\n<p><em><strong>Te puede interesar \ud83d\udc49\u00a0<a href=\"https:\/\/factorialhr.co\/blog\/mujeres-lideres-rrhh-8m\/\">10 mujeres l\u00edderes de Recursos Humanos contra la desigualdad de g\u00e9nero<\/a><\/strong><\/em><\/p>\n<h2><b>Qu\u00e9 hacer si te cuesta que ser escuchado en el trabajo\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Si te sientes identificado con estas din\u00e1micas de clasificaci\u00f3n de estatus en un equipo de trabajo, es posible que te resulten un poco deprimentes. Lo primero que tienes que tener en cuenta es que estas din\u00e1micas se establecen de forma impl\u00edcita y por defecto, y no de forma consciente y activa. <strong>Enfadarte con tus compa\u00f1eros no es una buena idea, ya que seguramente ellos no est\u00e1n d\u00e1ndose cuenta de que est\u00e1n actuando de esa manera y tus quejas pueden resultarles una sorpresa<\/strong>. Es muy posible adem\u00e1s que tus compa\u00f1eros y compa\u00f1eras no crean conscientemente en los estereotipos que, sin embargo, est\u00e1n aplicando.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por suerte hay algunas acciones que puedes poner en pr\u00e1ctica para intentar subvertir estas normas y <a href=\"https:\/\/factorialhr.co\/blog\/habilidades-blandas\/\">ganar el espacio<\/a> que realmente te mereces, en otras palabras, ser escuchado en el trabajo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una forma de aumentar tu estatus relativo es aprovechar aspectos como tu experiencia en el tema de discusi\u00f3n, tus logros pasados sobre el tema que sean relevantes para el equipo o la experiencia relevante sobre el mismo, mejor todav\u00eda si est\u00e1 vinculada a una marca o a una persona conocida.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este sentido, para aumentar tu estatus en la pr\u00f3xima reuni\u00f3n, los expertos recomiendan centrarse en uno de los temas que se vayan a tratar y planificar c\u00f3mo contribuir\u00e1s al mismo para as\u00ed tratar de incrementar tu estatus en relaci\u00f3n con ese tema.\u00a0<\/span><\/p>\n \n <!--HubSpot Call-to-Action Code -->\n    <span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-07c5414f-82b2-4e7e-81df-e88a224cb3f1\">\n        <span class=\"hs-cta-node hs-cta-07c5414f-82b2-4e7e-81df-e88a224cb3f1\" id=\"07c5414f-82b2-4e7e-81df-e88a224cb3f1\">\n            <a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/4960096\/07c5414f-82b2-4e7e-81df-e88a224cb3f1\">\n                <img decoding=\"async\" class=\"lazyload hs-cta-img\" id=\"hs-cta-img-07c5414f-82b2-4e7e-81df-e88a224cb3f1\" style=\"border-width:0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4960096\/07c5414f-82b2-4e7e-81df-e88a224cb3f1.png\"  alt=\"\u201csolicitud\" width=\"\u201c900\u201d\" height=\"\u201c308\u201d\" \/>\n            <\/a>\n        <\/span>\n        <script type=\"text\/javascript\">\n            function loadCTA(){\n                window.hbspt.cta.load(4960096, '07c5414f-82b2-4e7e-81df-e88a224cb3f1', {'region': 'eu1'})\n            }\n            if(window.hbspt){\n                loadCTA()\n            }else{\n                Defer.js(\n                    'https:\/\/js.hubspot.com\/cta\/current.js',\n                    'hubspotCTA', \n                    0, \n                    loadCTA\n                );\n            }\n        <\/script>\n    <\/span>\n<!-- end HubSpot Call-to-Action Code -->\n\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n puedes preparar algunos datos o hechos relevantes en relaci\u00f3n a ese tema para comentarlos en la reuni\u00f3n. <strong>Si lo haces de forma clara y confiada, tu estatus dentro del grupo subir\u00e1.<\/strong> Finalmente, piensa tambi\u00e9n de qu\u00e9 manera presentar\u00e1s la nueva informaci\u00f3n ya que es muy importante que el grupo perciba tu participaci\u00f3n para que aumente tu estatus.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En resumen, es importante ser consciente de que los miembros del grupo que no te escuchan probablemente no act\u00faan as\u00ed de forma intencionada, sino que todo el proceso puede haber ocurrido de manera inconsciente y ha partido de todo el grupo en su conjunto.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, si eres el <a href=\"https:\/\/factorialhr.co\/blog\/habilidades-de-un-lider\/\">responsable del equipo<\/a>, ten en cuenta que el hecho de que una persona tenga un estatus relativo bajo, puede frenarle a la hora de contribuir con ideas valiosas, pues siente que no es escuchado en el trabajo. Si consigues equilibrar los patrones de estatus entre los miembros de un mismo equipo, podr\u00e1s tener una variedad m\u00e1s amplia de ideas para ti y para tu equipo.<\/span><\/p>\n<p><span class=\"s1\">\u2705<\/span><span class=\"s2\"><b><\/b><a href=\"https:\/\/factorial.mx\/solicitar-demo\"><span class=\"s3\"><b>\u00a1Reg\u00edstrate y obt\u00e9n una asesor\u00eda gratis en Factorial. \u00danete a la digitalizaci\u00f3n de Recursos Humanos con nuestro software!<\/b><\/span><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Te damos algunos trucos para ser escuchado efectivamente en tu entorno de trabajo. Casi todos hemos sentido algo as\u00ed: estamos en una reuni\u00f3n, decimos algo, pero parece que las personas a nuestro alrededor siguen hablando como si tal cosa, como si no nos hubieran escuchado.\u00a0 Esta situaci\u00f3n, que puede ocurrir en nuestra vida diaria, es<a href=\"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/\" class=\"read-more\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":179,"featured_media":101410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[315],"tags":[],"class_list":["post-101335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos-2"],"acf":{"topics":"engagement"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.9.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu\u00e9 hacer si sientes que no eres escuchado en las reuniones de trabajo | Factorial<\/title>\n<meta name=\"description\" content=\"Conoce los consejos para ser escuchado en el trabajo. Si eres l\u00edder, garantiza una distribuci\u00f3n equitativa de la participaci\u00f3n de tu equipo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 hacer si sientes que no eres escuchado en las reuniones de trabajo\" \/>\n<meta property=\"og:description\" content=\"Conoce los consejos para ser escuchado en el trabajo. Si eres l\u00edder, garantiza una distribuci\u00f3n equitativa de la participaci\u00f3n de tu equipo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/\" \/>\n<meta property=\"og:site_name\" content=\"Factorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-09T11:58:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-19T13:01:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/factorialhr.co\/wp-content\/uploads\/2023\/05\/03151848\/Que-hacer-si-sientes-que-no-te-escuchan-en-el-trabajo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juanjo Villalba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@factorialapp\" \/>\n<meta name=\"twitter:site\" content=\"@factorialapp\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juanjo Villalba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/\"},\"author\":{\"name\":\"Juanjo Villalba\",\"@id\":\"https:\/\/factorialhr.co\/blog\/#\/schema\/person\/e6546176671e7b921fae1e683f79d27c\"},\"headline\":\"Qu\u00e9 hacer si sientes que no eres escuchado en las reuniones de trabajo\",\"datePublished\":\"2023-05-09T11:58:05+00:00\",\"dateModified\":\"2023-05-19T13:01:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/\"},\"wordCount\":1370,\"publisher\":{\"@id\":\"https:\/\/factorialhr.co\/blog\/#organization\"},\"articleSection\":[\"Consejos\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/\",\"url\":\"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/\",\"name\":\"Qu\u00e9 hacer si sientes que no eres escuchado en las reuniones de trabajo | Factorial\",\"isPartOf\":{\"@id\":\"https:\/\/factorialhr.co\/blog\/#website\"},\"datePublished\":\"2023-05-09T11:58:05+00:00\",\"dateModified\":\"2023-05-19T13:01:14+00:00\",\"description\":\"Conoce los consejos para ser escuchado en el trabajo. Si eres l\u00edder, garantiza una distribuci\u00f3n equitativa de la participaci\u00f3n de tu equipo.\",\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/factorialhr.co\/blog\/#website\",\"url\":\"https:\/\/factorialhr.co\/blog\/\",\"name\":\"Factorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/factorialhr.co\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/factorialhr.co\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/factorialhr.co\/blog\/#organization\",\"name\":\"All-in-one business management software - Factorial\",\"url\":\"https:\/\/factorialhr.co\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/factorialhr.co\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/factorialhr.co\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"contentUrl\":\"https:\/\/factorialhr.co\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"width\":946,\"height\":880,\"caption\":\"All-in-one business management software - Factorial\"},\"image\":{\"@id\":\"https:\/\/factorialhr.co\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\",\"https:\/\/twitter.com\/factorialapp\",\"https:\/\/www.linkedin.com\/company\/factorialhr\",\"https:\/\/www.youtube.com\/@factorialmedia\",\"https:\/\/www.instagram.com\/factorial\/#\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/factorialhr.co\/blog\/#\/schema\/person\/e6546176671e7b921fae1e683f79d27c\",\"name\":\"Juanjo Villalba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/factorialhr.co\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/89f18f859aa173964ebb48554de92105?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/89f18f859aa173964ebb48554de92105?s=96&d=identicon&r=g\",\"caption\":\"Juanjo Villalba\"},\"description\":\"Periodista freelance de Barcelona especializado en econom\u00eda, tecnolog\u00eda, lifestyle, cultura y relaciones. Fue Director editorial de Vice Espa\u00f1a y su trabajo ha aparecido en medios como El Pa\u00eds, El Peri\u00f3dico de Espa\u00f1a, S Moda, Vice y Yorokobu, entre otros.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/juanjo-villalba-a0005914\/\"],\"url\":\"https:\/\/factorialhr.co\/blog\/author\/juanjo-villalba\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qu\u00e9 hacer si sientes que no eres escuchado en las reuniones de trabajo | Factorial","description":"Conoce los consejos para ser escuchado en el trabajo. Si eres l\u00edder, garantiza una distribuci\u00f3n equitativa de la participaci\u00f3n de tu equipo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 hacer si sientes que no eres escuchado en las reuniones de trabajo","og_description":"Conoce los consejos para ser escuchado en el trabajo. Si eres l\u00edder, garantiza una distribuci\u00f3n equitativa de la participaci\u00f3n de tu equipo.","og_url":"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/","og_site_name":"Factorial","article_publisher":"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","article_published_time":"2023-05-09T11:58:05+00:00","article_modified_time":"2023-05-19T13:01:14+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/factorialhr.co\/wp-content\/uploads\/2023\/05\/03151848\/Que-hacer-si-sientes-que-no-te-escuchan-en-el-trabajo.jpg","type":"image\/jpeg"}],"author":"Juanjo Villalba","twitter_card":"summary_large_image","twitter_creator":"@factorialapp","twitter_site":"@factorialapp","twitter_misc":{"Written by":"Juanjo Villalba","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/#article","isPartOf":{"@id":"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/"},"author":{"name":"Juanjo Villalba","@id":"https:\/\/factorialhr.co\/blog\/#\/schema\/person\/e6546176671e7b921fae1e683f79d27c"},"headline":"Qu\u00e9 hacer si sientes que no eres escuchado en las reuniones de trabajo","datePublished":"2023-05-09T11:58:05+00:00","dateModified":"2023-05-19T13:01:14+00:00","mainEntityOfPage":{"@id":"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/"},"wordCount":1370,"publisher":{"@id":"https:\/\/factorialhr.co\/blog\/#organization"},"articleSection":["Consejos"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/","url":"https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/","name":"Qu\u00e9 hacer si sientes que no eres escuchado en las reuniones de trabajo | Factorial","isPartOf":{"@id":"https:\/\/factorialhr.co\/blog\/#website"},"datePublished":"2023-05-09T11:58:05+00:00","dateModified":"2023-05-19T13:01:14+00:00","description":"Conoce los consejos para ser escuchado en el trabajo. Si eres l\u00edder, garantiza una distribuci\u00f3n equitativa de la participaci\u00f3n de tu equipo.","inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/factorialhr.co\/blog\/ser-escuchados-trabajo\/"]}]},{"@type":"WebSite","@id":"https:\/\/factorialhr.co\/blog\/#website","url":"https:\/\/factorialhr.co\/blog\/","name":"Factorial","description":"","publisher":{"@id":"https:\/\/factorialhr.co\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/factorialhr.co\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/factorialhr.co\/blog\/#organization","name":"All-in-one business management software - Factorial","url":"https:\/\/factorialhr.co\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/factorialhr.co\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/factorialhr.co\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","contentUrl":"https:\/\/factorialhr.co\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","width":946,"height":880,"caption":"All-in-one business management software - Factorial"},"image":{"@id":"https:\/\/factorialhr.co\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","https:\/\/twitter.com\/factorialapp","https:\/\/www.linkedin.com\/company\/factorialhr","https:\/\/www.youtube.com\/@factorialmedia","https:\/\/www.instagram.com\/factorial\/#"]},{"@type":"Person","@id":"https:\/\/factorialhr.co\/blog\/#\/schema\/person\/e6546176671e7b921fae1e683f79d27c","name":"Juanjo Villalba","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/factorialhr.co\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/89f18f859aa173964ebb48554de92105?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/89f18f859aa173964ebb48554de92105?s=96&d=identicon&r=g","caption":"Juanjo Villalba"},"description":"Periodista freelance de Barcelona especializado en econom\u00eda, tecnolog\u00eda, lifestyle, cultura y relaciones. Fue Director editorial de Vice Espa\u00f1a y su trabajo ha aparecido en medios como El Pa\u00eds, El Peri\u00f3dico de Espa\u00f1a, S Moda, Vice y Yorokobu, entre otros.","sameAs":["https:\/\/www.linkedin.com\/in\/juanjo-villalba-a0005914\/"],"url":"https:\/\/factorialhr.co\/blog\/author\/juanjo-villalba\/"}]}},"_links":{"self":[{"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/posts\/101335"}],"collection":[{"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/users\/179"}],"replies":[{"embeddable":true,"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/comments?post=101335"}],"version-history":[{"count":3,"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/posts\/101335\/revisions"}],"predecessor-version":[{"id":103850,"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/posts\/101335\/revisions\/103850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/media\/101410"}],"wp:attachment":[{"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/media?parent=101335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/categories?post=101335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/factorialhr.co\/blog\/wp-json\/wp\/v2\/tags?post=101335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}